{"id":69,"count":1,"description":"","link":"https:\/\/webzone.com.mx\/blog\/tag\/desarrollo-frontend\/","name":"desarrollo frontend","slug":"desarrollo-frontend","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/webzone.com.mx\/blog\/wp-json\/wp\/v2\/tags\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webzone.com.mx\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/webzone.com.mx\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/webzone.com.mx\/blog\/wp-json\/wp\/v2\/posts?tags=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}